{"id":10529,"date":"2025-07-29T13:13:48","date_gmt":"2025-07-29T16:13:48","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=10529"},"modified":"2025-07-29T13:13:49","modified_gmt":"2025-07-29T16:13:49","slug":"dospu-en-medio-de-una-crisis-proponen-acciones-para-recuperar-el-prestigio","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/dospu-en-medio-de-una-crisis-proponen-acciones-para-recuperar-el-prestigio\/","title":{"rendered":"Dospu: en medio de una crisis, proponen acciones para \u00abrecuperar\u00bb el prestigio"},"content":{"rendered":"\n<p>La Direcci\u00f3n de Obra Social del Personal Universitario (DOSPU) atraviesa una profunda crisis financiera e institucional. El ajuste en los sueldos universitarios por parte del Gobierno nacional y el aumento sostenido en los precios de los medicamentos han deteriorado el funcionamiento de la mutual. Frente a este escenario, el Consejo Normalizador present\u00f3 una propuesta integral para \u201crecuperar\u201d el prestigio perdido y reorganizar el sistema de salud universitario.<\/p>\n\n\n\n<p>Las iniciativas fueron discutidas en una asamblea integrada en su mayor\u00eda por ex presidentes de DOSPU, y ahora deber\u00e1n ser evaluadas por el Consejo Superior de la Universidad Nacional de San Luis (UNSL) el pr\u00f3ximo 5 de agosto. Entre las medidas destacadas, se encuentra el pedido de un pr\u00e9stamo al DECOM \u2014la caja compensadora del personal universitario\u2014, el aumento de la contribuci\u00f3n patronal del 6% al 8%, y la suba del aporte de los trabajadores activos del 3% al 6%, al menos hasta marzo de 2026.<\/p>\n\n\n\n<p>Eduardo Borkowski, miembro del Consejo Normalizador, afirm\u00f3 que \u201cno creemos que alguna medida aplicada de forma aislada conduzca a una buena soluci\u00f3n, sino que hay que aplicar todo en su conjunto\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n se propuso la creaci\u00f3n de una nueva conducci\u00f3n provisoria, el fortalecimiento del servicio de farmacia, la revisi\u00f3n de convenios vigentes y la mejora en la atenci\u00f3n y reintegros a los afiliados.<\/p>\n\n\n\n<p>Las propuestas surgen como respuesta al deterioro de las prestaciones y del v\u00ednculo con los afiliados, evidenciado en el balance 2024 DOSPU-DECOM y en un informe solicitado por m\u00e1s de 200 personas afiliadas. La comisi\u00f3n considera que es urgente adoptar decisiones \u201cracionales y verificables\u201d para evitar el colapso total del sistema.<\/p>\n\n\n\n<p>El proyecto incluye adem\u00e1s la suspensi\u00f3n transitoria de art\u00edculos de la carta org\u00e1nica que regulan la conducci\u00f3n de la obra social, para permitir el nombramiento de autoridades provisorias que trabajen ad honorem hasta marzo del 2026.<\/p>\n\n\n\n<p>La propuesta cierra con el pedido de designar al Consejo Normalizador como comisi\u00f3n permanente de seguimiento de DOSPU y DECOM, garantizando el control y la aplicaci\u00f3n del plan integral en su totalidad.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n de Obra Social del Personal Universitario (DOSPU) atraviesa una profunda crisis financiera e institucional. El ajuste en los sueldos universitarios por parte del Gobierno nacional y el aumento sostenido en los precios de los medicamentos han deteriorado el funcionamiento de la mutual. Frente a este escenario, el Consejo Normalizador present\u00f3 una propuesta integral &hellip;<\/p>\n","protected":false},"author":12,"featured_media":10530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[],"class_list":["post-10529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-luis"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/07\/dospu.jpg?fit=560%2C320&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/10529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=10529"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/10529\/revisions"}],"predecessor-version":[{"id":10531,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/10529\/revisions\/10531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/10530"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=10529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=10529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=10529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}