{"id":11142,"date":"2025-09-05T14:22:07","date_gmt":"2025-09-05T17:22:07","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=11142"},"modified":"2025-09-05T14:22:11","modified_gmt":"2025-09-05T17:22:11","slug":"ate-amenaza-con-un-paro-total-en-la-municipalidad-de-san-luis-ante-la-falta-de-aumento-salarial","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/ate-amenaza-con-un-paro-total-en-la-municipalidad-de-san-luis-ante-la-falta-de-aumento-salarial\/","title":{"rendered":"ATE amenaza con un paro total en la Municipalidad de San Luis ante la falta de aumento salarial"},"content":{"rendered":"\n<p>El Consejo Directivo Provincial de la Asociaci\u00f3n de Trabajadores del Estado (ATE) San Luis advirti\u00f3 que, tras tres d\u00edas de asambleas y retenci\u00f3n de tareas en once \u00e1reas de la Municipalidad de San Luis, podr\u00eda declararse un paro total de actividades si no hay respuesta al reclamo de recomposici\u00f3n salarial.<\/p>\n\n\n\n<p>Desde este lunes, los empleados municipales llevan adelante asambleas para exigir un incremento urgente de haberes, denunciando que los sueldos actuales se encuentran por debajo de la l\u00ednea de pobreza. \u201cLos aumentos otorgados hasta ahora no responden a la inflaci\u00f3n real\u201d, se\u00f1alaron desde ATE, y remarcaron que muchas familias municipales se ven obligadas a endeudarse para cubrir gastos b\u00e1sicos como alquiler, alimentos, transporte y medicamentos.<\/p>\n\n\n\n<p>Entre las demandas elevadas al Ejecutivo municipal figuran: aumento salarial, incorporaci\u00f3n de sumas no remunerativas al b\u00e1sico, recategorizaciones, pases a planta permanente, entrega de indumentaria laboral, igualdad en suplementos adicionales y mejoras en seguridad e higiene.<\/p>\n\n\n\n<p>La decisi\u00f3n final sobre un eventual paro total quedar\u00e1 en manos de las asambleas, que en las pr\u00f3ximas horas definir\u00e1n los pasos a seguir si no hay respuestas concretas por parte de las autoridades municipales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Directivo Provincial de la Asociaci\u00f3n de Trabajadores del Estado (ATE) San Luis advirti\u00f3 que, tras tres d\u00edas de asambleas y retenci\u00f3n de tareas en once \u00e1reas de la Municipalidad de San Luis, podr\u00eda declararse un paro total de actividades si no hay respuesta al reclamo de recomposici\u00f3n salarial. Desde este lunes, los empleados &hellip;<\/p>\n","protected":false},"author":13,"featured_media":11143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[],"class_list":["post-11142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-luis"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-05-at-14.21.07.jpeg?fit=1147%2C838&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=11142"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11142\/revisions"}],"predecessor-version":[{"id":11144,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11142\/revisions\/11144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/11143"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=11142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=11142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=11142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}