{"id":11496,"date":"2025-09-27T15:51:49","date_gmt":"2025-09-27T18:51:49","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=11496"},"modified":"2025-09-27T15:51:50","modified_gmt":"2025-09-27T18:51:50","slug":"tragedia-en-la-autopista-de-las-serranias-puntanas-dos-muertos-tras-un-choque-frontal","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/tragedia-en-la-autopista-de-las-serranias-puntanas-dos-muertos-tras-un-choque-frontal\/","title":{"rendered":"Tragedia en la Autopista de las Serran\u00edas Puntanas: dos muertos tras un choque frontal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La noche del viernes se produjo un violento accidente en el <strong>kil\u00f3metro 793 de la Autopista de las Serran\u00edas Puntanas<\/strong>, a la altura del Aut\u00f3dromo Provincial <em>\u201cRosendo Hern\u00e1ndez\u201d<\/em>. El siniestro dej\u00f3 como saldo la muerte de dos hombres que viajaban en un autom\u00f3vil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la <strong>Direcci\u00f3n General de Polic\u00eda Caminera y Seguridad Vial<\/strong>, el hecho ocurri\u00f3 alrededor de las 22:30, cuando un <strong>Volkswagen Sur\u00e1n<\/strong> impact\u00f3 de frente contra un <strong>cami\u00f3n Scania<\/strong>. Los ocupantes del veh\u00edculo menor, de <strong>63 y 22 a\u00f1os<\/strong>, fallecieron en el acto. Sus identidades permanecen en proceso de confirmaci\u00f3n oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cami\u00f3n era conducido por un joven de 23 a\u00f1os, quien sali\u00f3 ileso del choque. El test de alcoholemia realizado en el lugar arroj\u00f3 <strong>0,00 g\/l de alcohol en sangre<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el operativo trabaj\u00f3 personal de <strong>Bomberos del Cuartel I<\/strong>, que cort\u00f3 el suministro de GNC del rodado menor y constat\u00f3 el deceso de las v\u00edctimas. Posteriormente, los cuerpos fueron trasladados al Hospital <em>\u201cDr. Ram\u00f3n Carrillo\u201d<\/em> para su identificaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto el autom\u00f3vil como el cami\u00f3n quedaron secuestrados a fin de realizar las <strong>pericias accidentol\u00f3gicas<\/strong> correspondientes, que determinar\u00e1n las causas del fatal choque.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noche del viernes se produjo un violento accidente en el kil\u00f3metro 793 de la Autopista de las Serran\u00edas Puntanas, a la altura del Aut\u00f3dromo Provincial \u201cRosendo Hern\u00e1ndez\u201d. El siniestro dej\u00f3 como saldo la muerte de dos hombres que viajaban en un autom\u00f3vil. De acuerdo con la Direcci\u00f3n General de Polic\u00eda Caminera y Seguridad Vial, &hellip;<\/p>\n","protected":false},"author":12,"featured_media":11497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[47,32],"tags":[],"class_list":["post-11496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales-y-judiciales","category-san-luis"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-27-at-15.48.39.jpeg?fit=683%2C440&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=11496"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11496\/revisions"}],"predecessor-version":[{"id":11498,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/11496\/revisions\/11498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/11497"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=11496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=11496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=11496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}