{"id":12139,"date":"2025-11-08T16:31:43","date_gmt":"2025-11-08T19:31:43","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=12139"},"modified":"2025-11-08T16:33:52","modified_gmt":"2025-11-08T19:33:52","slug":"acusan-al-director-del-pediatrico-y-a-la-ministra-de-salud-de-dirigencia-irregular-en-el-sistema-sanitario","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/acusan-al-director-del-pediatrico-y-a-la-ministra-de-salud-de-dirigencia-irregular-en-el-sistema-sanitario\/","title":{"rendered":"Acusan al director del Pedi\u00e1trico y a la ministra de Salud de dirigencia irregular en el sistema sanitario"},"content":{"rendered":"\n<p>Una denuncia formal presentada por trabajadores del sector sanitario provincial involucra al director del Hospital Pedi\u00e1trico y a la ministra de Salud en una serie de acusaciones que incluyen favoritismos, malos tratos al personal y decisiones administrativas consideradas arbitrarias.<\/p>\n\n\n\n<p>Seg\u00fan los denunciantes, la gesti\u00f3n del nosocomio habr\u00eda favorecido nombramientos y contrataciones vinculadas a allegados de la direcci\u00f3n, al mismo tiempo que se observar\u00edan irregularidades en los procesos internos, como la falta de transparencia para cubrir vacantes, y condiciones laborales adversas para el personal de base.<\/p>\n\n\n\n<p>La denuncia sostiene que la ministra de Salud tendr\u00eda conocimiento de estas pr\u00e1cticas y, pese a ello, no habr\u00eda tomado medidas correctivas efectivas. Esta falta de acci\u00f3n incrementa la preocupaci\u00f3n del personal afectado, que afirma estar sometido a ambientes de trabajo hostiles y a presiones por sumisi\u00f3n.<\/p>\n\n\n\n<p>Entre otras acusaciones, se menciona que se habr\u00edan impuesto sanciones sin causa aparente, quienes reclamaron mejoras enfrentaron amenazas de despido o traslados arbitrarios, y que se habr\u00edan tomado decisiones sobre infraestructura y equipamiento sin consulta previa con el equipo m\u00e9dico.<\/p>\n\n\n\n<p>Los trabajadores que firmaron el escrito solicitaron la intervenci\u00f3n de organismos de control, tanto administrativos como judiciales, y exigieron que se garantice la transparencia en los ascensos, contrataciones y asignaci\u00f3n de recursos del hospital y la cartera de salud. Adem\u00e1s, advierten que la situaci\u00f3n ya afecta la atenci\u00f3n al p\u00fablico y la calidad del servicio sanitario.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una denuncia formal presentada por trabajadores del sector sanitario provincial involucra al director del Hospital Pedi\u00e1trico y a la ministra de Salud en una serie de acusaciones que incluyen favoritismos, malos tratos al personal y decisiones administrativas consideradas arbitrarias. Seg\u00fan los denunciantes, la gesti\u00f3n del nosocomio habr\u00eda favorecido nombramientos y contrataciones vinculadas a allegados de &hellip;<\/p>\n","protected":false},"author":12,"featured_media":12142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32],"tags":[],"class_list":["post-12139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-luis"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2024-07-17-at-12.26.18-750x420-1.jpeg?fit=750%2C420&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=12139"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12139\/revisions"}],"predecessor-version":[{"id":12141,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12139\/revisions\/12141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/12142"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=12139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=12139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=12139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}