{"id":12441,"date":"2025-11-25T13:41:23","date_gmt":"2025-11-25T16:41:23","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=12441"},"modified":"2025-11-25T13:41:24","modified_gmt":"2025-11-25T16:41:24","slug":"francisco-ledesma-advierte-que-la-designacion-de-presti-apunta-contra-los-derechos-humanos","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/francisco-ledesma-advierte-que-la-designacion-de-presti-apunta-contra-los-derechos-humanos\/","title":{"rendered":"Francisco Ledesma advierte que la designaci\u00f3n de Presti apunta contra los derechos humanos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Francisco Ledesma, hermano de uno de los desaparecidos durante la \u00faltima dictadura militar, sostuvo que la reciente designaci\u00f3n de <strong>Presti<\/strong> no es un hecho aislado, sino parte de un \u201cplan sistem\u00e1tico\u201d contra los derechos humanos. Seg\u00fan Ledesma, la elecci\u00f3n de Presti responde a una estrategia pol\u00edtica con ra\u00edces profundas que podr\u00eda debilitar los mecanismos de memoria, verdad y justicia en la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ledesma se\u00f1al\u00f3 que esta designaci\u00f3n simboliza un avance preocupante: no solo representa un giro institucional, sino tambi\u00e9n una voluntad de erosionar el legado de las v\u00edctimas del terrorismo de Estado. Para \u00e9l, es una se\u00f1al de que ciertos sectores pretenden relegar la defensa de los derechos humanos a un segundo plano, abriendo la puerta a pol\u00edticas m\u00e1s conservadoras y menos sensibles a las demandas hist\u00f3ricas de reparaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su discurso p\u00fablico, Ledesma hizo un llamado al compromiso de la sociedad para no normalizar decisiones que comprometan la memoria colectiva. Inst\u00f3 a las organizaciones de derechos humanos, a los organismos estatales y a la ciudadan\u00eda a estar vigilantes y a exigir transparencia. Para \u00e9l, preservar los derechos fundamentales no es solo una cuesti\u00f3n simb\u00f3lica, sino una obligaci\u00f3n concreta que debe traducirse en acciones institucionales y pol\u00edticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pol\u00e9mica no solo reaviva viejos debates sobre la reconciliaci\u00f3n y la justicia: tambi\u00e9n plantea dudas sobre el rumbo futuro de las pol\u00edticas de derechos humanos en San Luis. Para Ledesma, esta designaci\u00f3n no debe verse como un hecho t\u00e9cnico, sino como una se\u00f1al de una nueva etapa con desaf\u00edos crecientes para la memoria democr\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francisco Ledesma, hermano de uno de los desaparecidos durante la \u00faltima dictadura militar, sostuvo que la reciente designaci\u00f3n de Presti no es un hecho aislado, sino parte de un \u201cplan sistem\u00e1tico\u201d contra los derechos humanos. Seg\u00fan Ledesma, la elecci\u00f3n de Presti responde a una estrategia pol\u00edtica con ra\u00edces profundas que podr\u00eda debilitar los mecanismos de &hellip;<\/p>\n","protected":false},"author":13,"featured_media":12442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[29],"tags":[],"class_list":["post-12441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-25-at-13.37.43.jpeg?fit=766%2C520&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=12441"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12441\/revisions"}],"predecessor-version":[{"id":12443,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/12441\/revisions\/12443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/12442"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=12441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=12441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=12441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}