{"id":2559,"date":"2024-12-03T11:22:51","date_gmt":"2024-12-03T14:22:51","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=2559"},"modified":"2024-12-03T11:22:51","modified_gmt":"2024-12-03T14:22:51","slug":"kicillof-milei-considera-que-la-justicia-social-es-una-aberracion","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/kicillof-milei-considera-que-la-justicia-social-es-una-aberracion\/","title":{"rendered":"Kicillof: \u00abMilei considera que la justicia social es una aberraci\u00f3n\u00bb"},"content":{"rendered":"<p>El gobernador bonaerense, Axel Kicillof, llam\u00f3 hoy a no votar por el candidato presidencial de La Libertad Avanza, Javier MIlei, en el balotaje del pr\u00f3ximo 19 de noviembre y resalt\u00f3 la necesidad de \u00abreparar injusticias y construir bienestar\u00bb.<\/p>\n<p><!--more--><\/p>\n<p>\u00abMilei considera que la justicia social es una aberraci\u00f3n, cuando todos sabemos que en este pa\u00eds hay algunos pocos que concentran la riqueza\u00bb, poste\u00f3 el mandatario en sus redes sociales y agreg\u00f3 el hashtag: #FrenemosLaLocura, al igual que otros referentes del oficialismo.<\/p>\n<p>Luego, expres\u00f3 que \u00abla sociedad demanda y necesita pol\u00edticas firmes y decididas para reparar injusticias y construir bienestar\u00bb y analiz\u00f3 que \u00abno se trata de quitar derechos, se trata de generar oportunidades e igualdad\u00bb.<\/p>\n<p>El gobernador agreg\u00f3 un video en el que se puede observar c\u00f3mo, por un lado, el postulante libertario se refiere a la justicia socia como una \u00abatrocidad\u00bb dado que \u00abalguien tiene que pagar para cumplir los derechos\u00bb de la gente; mientras que, por el otro, Kicillof destaca que \u00abdonde hay una necesidad dentro de la sociedad debe aparecer una respuesta del Estado\u00bb<\/p>\n<p>\u00abNi atr\u00e1s ni a la derecha. Derecho al futuro\u00bb, se puede leer en el final del material audiovisual, en el que se muestran im\u00e1genes de Kicillof inaugurando escuelas, entregando viviendas y recorriendo obras p\u00fablicas y se cierra con el lema: \u00abNo a Milei\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador bonaerense, Axel Kicillof, llam\u00f3 hoy a no votar por el candidato presidencial de La Libertad Avanza, Javier MIlei, en el balotaje del pr\u00f3ximo 19 de noviembre y resalt\u00f3 la necesidad de \u00abreparar injusticias y construir bienestar\u00bb. \u00abMilei considera que la justicia social es una aberraci\u00f3n, cuando todos sabemos que en este pa\u00eds hay &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-2559","post","type-post","status-publish","format-standard","hentry","category-calle-angosta"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=2559"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2559\/revisions"}],"predecessor-version":[{"id":6905,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2559\/revisions\/6905"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=2559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=2559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=2559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}