{"id":2850,"date":"2024-12-03T10:42:41","date_gmt":"2024-12-03T13:42:41","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=2850"},"modified":"2024-12-03T11:11:54","modified_gmt":"2024-12-03T14:11:54","slug":"san-luis-afronta-una-semana-crucial-con-malestar-creciente","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/san-luis-afronta-una-semana-crucial-con-malestar-creciente\/","title":{"rendered":"San Luis afronta una semana crucial con malestar creciente"},"content":{"rendered":"<p>El gobernador de San Luis, Claudio Poggi, se enfrenta a una semana crucial tras la aplicaci\u00f3n de severas medidas econ\u00f3micas que han desatado una profunda crisis en la provincia. La primera \u00abcuota\u00bb salarial para los estatales se abonar\u00e1 el viernes, generando malestar por el cese del \u00abTratado de La Toma\u00bb y la falta de pago de la coparticipaci\u00f3n, impactando a municipios y empleados p\u00fablicos.<\/p>\n<p><!--more--><\/p>\n<p>El desdoblamiento salarial, anunciado como respuesta a un supuesto d\u00e9ficit fiscal heredado, ser\u00e1 una prueba de fuego. Los empleados estatales percibir\u00e1n solo la mitad de sus salarios por primera vez en la historia democr\u00e1tica de San Luis, generando trastornos econ\u00f3micos en un contexto de inflaci\u00f3n descontrolada.<\/p>\n<p>El informe del exministro de Hacienda, Eloy Horcajo, contradice la narrativa gubernamental. Detalla un cierre de 2023 sin deudas y con saldo positivo, incluyendo una canasta de inversiones de 30 millones de d\u00f3lares. A pesar de esto, Poggi propone tomar deuda por 150 mil millones de pesos.<\/p>\n<p>La ausencia de documentos que respalden el supuesto d\u00e9ficit contrasta con el informe de Horcajo y ha llevado a cr\u00edticas. La medida, que colisiona con derechos laborales y se considera inconstitucional, ha generado repudio en la sociedad puntana y manifestaciones contra el ajuste.<\/p>\n<p>El presidente provisional del Senado de la Naci\u00f3n, Bartolom\u00e9 Abdala, expres\u00f3 sorpresa por la situaci\u00f3n financiera de San Luis, una provincia que manten\u00eda equilibrio fiscal durante d\u00e9cadas. La transformaci\u00f3n de una provincia con obras en marcha a una econom\u00eda de guerra en poco tiempo ha desconcertado a propios y extra\u00f1os.<\/p>\n<p>El repudio a las medidas se ha materializado en marchas y ollas populares, mientras legisladores del Frente Unidad Justicialista han enviado cartas documentos intimando al gobernador a abonar la totalidad de los salarios antes del 31 de diciembre, amenazando con denuncias por retenci\u00f3n indebida de fondos.<\/p>\n<p>El desdoblamiento salarial y otras acciones del gobierno generan incertidumbre en San Luis, marcando un cambio abrupto en la realidad econ\u00f3mica y social de la provincia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de San Luis, Claudio Poggi, se enfrenta a una semana crucial tras la aplicaci\u00f3n de severas medidas econ\u00f3micas que han desatado una profunda crisis en la provincia. La primera \u00abcuota\u00bb salarial para los estatales se abonar\u00e1 el viernes, generando malestar por el cese del \u00abTratado de La Toma\u00bb y la falta de pago &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-2850","post","type-post","status-publish","format-standard","hentry","category-calle-angosta"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=2850"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2850\/revisions"}],"predecessor-version":[{"id":6616,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/2850\/revisions\/6616"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=2850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=2850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=2850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}