{"id":7357,"date":"2024-12-19T13:48:55","date_gmt":"2024-12-19T16:48:55","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=7357"},"modified":"2024-12-26T11:35:02","modified_gmt":"2024-12-26T14:35:02","slug":"san-luis-expertos-cuestionan-la-tasa-de-desocupacion-reportada-por-el-indec","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/san-luis-expertos-cuestionan-la-tasa-de-desocupacion-reportada-por-el-indec\/","title":{"rendered":"San Luis: expertos cuestionan la tasa de desocupaci\u00f3n reportada por el INDEC"},"content":{"rendered":"\n<p>El Instituto Nacional de Estad\u00edstica y Censos (INDEC) inform\u00f3 este mi\u00e9rcoles que la desocupaci\u00f3n en San Luis se mantuvo en un 4,1% durante el tercer trimestre de 2024. Sin embargo, el contador Hugo Zudaire expres\u00f3 dudas sobre la fiabilidad de este \u00edndice, se\u00f1alando que la recesi\u00f3n econ\u00f3mica y el desplazamiento del empleo registrado al no registrado distorsionan el panorama laboral real.<\/p>\n\n\n\n<p>Seg\u00fan Zudaire, la ca\u00edda del consumo, estimada entre un 15% y un 20%, es un factor determinante que ha impactado en el empleo formal. \u201cMenor consumo significa menor producci\u00f3n y, en consecuencia, menor demanda laboral. Esto nos lleva a prever un aumento en la tasa de desocupaci\u00f3n real\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>El especialista destac\u00f3 que el \u00edndice oficial solo mide a la poblaci\u00f3n econ\u00f3micamente activa (PEA) y, dentro de esta, el empleo registrado. Sin embargo, asegur\u00f3 que tambi\u00e9n ha habido un retroceso en el empleo informal, lo que no se refleja en las estad\u00edsticas oficiales.<\/p>\n\n\n\n<p>\u201cEs dif\u00edcil aceptar que, en un contexto de recesi\u00f3n econ\u00f3mica donde la actividad cay\u00f3 entre un 10% y un 20%, la tasa de desocupaci\u00f3n en San Luis siga en el 4,1%. Algo no cierra\u201d, subray\u00f3.<\/p>\n\n\n\n<p>Hist\u00f3ricamente, Zudaire explic\u00f3 que la desocupaci\u00f3n estructural en Argentina se ubicaba alrededor del 3%. Sin embargo, en la actualidad, esa cifra ha subido al 7%, seg\u00fan sus estimaciones. Esto hace a\u00fan m\u00e1s improbable que la provincia de San Luis, en una econom\u00eda tan golpeada, registre un \u00edndice tan bajo.<\/p>\n\n\n\n<p>El debate sobre la fiabilidad de las cifras de desempleo refleja la necesidad de observar m\u00e1s all\u00e1 de los n\u00fameros y considerar el impacto real de la crisis econ\u00f3mica en la poblaci\u00f3n trabajadora de la provincia.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional de Estad\u00edstica y Censos (INDEC) inform\u00f3 este mi\u00e9rcoles que la desocupaci\u00f3n en San Luis se mantuvo en un 4,1% durante el tercer trimestre de 2024. Sin embargo, el contador Hugo Zudaire expres\u00f3 dudas sobre la fiabilidad de este \u00edndice, se\u00f1alando que la recesi\u00f3n econ\u00f3mica y el desplazamiento del empleo registrado al no &hellip;<\/p>\n","protected":false},"author":13,"featured_media":7358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32,17],"tags":[],"class_list":["post-7357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-luis","category-sociedad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2024\/12\/descarga-62.jpg?fit=275%2C183&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/7357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=7357"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/7357\/revisions"}],"predecessor-version":[{"id":7359,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/7357\/revisions\/7359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/7358"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=7357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=7357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=7357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}