{"id":8746,"date":"2025-03-24T13:05:06","date_gmt":"2025-03-24T16:05:06","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=8746"},"modified":"2025-03-24T13:05:07","modified_gmt":"2025-03-24T16:05:07","slug":"en-villa-mercedes-movilizacion-y-acto-cultural-en-conmemoracion-del-24-de-marzo","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/en-villa-mercedes-movilizacion-y-acto-cultural-en-conmemoracion-del-24-de-marzo\/","title":{"rendered":"En Villa Mercedes: Movilizaci\u00f3n y Acto Cultural en Conmemoraci\u00f3n del 24 de Marzo"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>Movilizaci\u00f3n contra el Gobierno Estafador<\/strong><\/h4>\n\n\n\n<p>El pr\u00f3ximo lunes 24 de marzo, se llevar\u00e1 a cabo una movilizaci\u00f3n hist\u00f3rica en la Plaza San Mart\u00edn de Villa Mercedes, San Luis, a las 17 hs. El evento est\u00e1 organizado por el Multisectorial por la Memoria (VM), un colectivo que trabaja incansablemente para mantener viva la memoria de los desaparecidos durante la \u00faltima dictadura militar argentina.<\/p>\n\n\n\n<p>La convocatoria tiene como lema principal: <strong>\u00abLibertad y Revoluci\u00f3n son nuestras: \u00a1Fuera, Gobierno Estafador!\u00bb <\/strong>, reflejando no solo el reclamo por justicia y verdad sobre los cr\u00edmenes cometidos en el pasado, sino tambi\u00e9n la necesidad de denunciar las pol\u00edticas actuales que consideran perjudiciales para la sociedad. La consigna \u00abLa memoria no se suspende\u00bb subraya la importancia de mantener vivo el recuerdo de las v\u00edctimas y seguir exigiendo justicia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"600\" data-attachment-id=\"8747\" data-permalink=\"https:\/\/calleangosta.com\/ca\/en-villa-mercedes-movilizacion-y-acto-cultural-en-conmemoracion-del-24-de-marzo\/plaza\/\" data-orig-file=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"plaza\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?fit=480%2C600&amp;ssl=1\" data-id=\"8747\" src=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?resize=480%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-8747\" srcset=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?resize=480%2C600&amp;ssl=1 480w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?resize=120%2C150&amp;ssl=1 120w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Acto Cultural con Entrada Gratuita<\/strong><\/h4>\n\n\n\n<p>En paralelo a la movilizaci\u00f3n, el mismo d\u00eda, pero a las 20 hs., se realizar\u00e1 un acto cultural en el Teatro TIM de Villa Mercedes. Este evento contar\u00e1 con entrada gratuita y estar\u00e1 dedicado a la tem\u00e1tica de <strong>memoria, verdad y justicia siempre <\/strong>, palabras que resuenan como un llamado constante a no olvidar ni perdonar los horrores del pasado.<\/p>\n\n\n\n<p>El acto cultural busca ser un espacio donde la comunidad pueda reflexionar y honrar a las v\u00edctimas de la dictadura c\u00edvico-militar, as\u00ed como tambi\u00e9n fortalecer el compromiso con la lucha por los derechos humanos. A trav\u00e9s de expresiones art\u00edsticas, poes\u00eda, m\u00fasica y testimonios, se pretende crear un ambiente de solidaridad y reivindicaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"600\" data-attachment-id=\"8748\" data-permalink=\"https:\/\/calleangosta.com\/ca\/en-villa-mercedes-movilizacion-y-acto-cultural-en-conmemoracion-del-24-de-marzo\/teatro\/\" data-orig-file=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?fit=1423%2C1600&amp;ssl=1\" data-orig-size=\"1423,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"teatro\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?fit=534%2C600&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=534%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-8748\" srcset=\"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=534%2C600&amp;ssl=1 534w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=267%2C300&amp;ssl=1 267w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=133%2C150&amp;ssl=1 133w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=768%2C864&amp;ssl=1 768w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?resize=1366%2C1536&amp;ssl=1 1366w, https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/teatro.jpeg?w=1423&amp;ssl=1 1423w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Un D\u00eda de Reivindicaci\u00f3n y Reflexi\u00f3n<\/strong><\/h4>\n\n\n\n<p>El 24 de marzo es un d\u00eda emblem\u00e1tico en la historia argentina, ya que marca el inicio de la \u00faltima dictadura militar, ocurrida entre 1976 y 1983. Durante este per\u00edodo, miles de personas fueron secuestradas, torturadas y asesinadas, mientras que otras tantas fueron forzadas al exilio. Hoy, m\u00e1s de cuatro d\u00e9cadas despu\u00e9s, las organizaciones de derechos humanos contin\u00faan su lucha por la verdad, la justicia y la memoria.<\/p>\n\n\n\n<p>Este a\u00f1o, la convocatoria en Villa Mercedes toma especial relevancia, ya que busca unir a las generaciones en torno a un objetivo com\u00fan: recordar, exigir y construir un futuro basado en los principios de libertad, justicia y dignidad humana.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Invitaci\u00f3n a la Participaci\u00f3n<\/strong><\/h4>\n\n\n\n<p>Se invita a toda la comunidad a participar tanto en la movilizaci\u00f3n como en el acto cultural. Ambos eventos buscan generar un espacio de unidad y resistencia, donde cada persona pueda contribuir con su presencia y voz. La entrada al acto cultural es gratuita, lo que facilita la participaci\u00f3n de todos aquellos interesados en rendir homenaje a las v\u00edctimas y apoyar la causa de los derechos humanos.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Resumen de Datos Clave<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fecha: <\/strong>Lunes 24 de marzo de 2025<\/li>\n\n\n\n<li><strong>Hora de la Movilizaci\u00f3n: <\/strong>17 hs.<\/li>\n\n\n\n<li><strong>Lugar de la Movilizaci\u00f3n: <\/strong>Plaza San Mart\u00edn, Villa Mercedes &#8211; San Luis<\/li>\n\n\n\n<li><strong>Organizador: <\/strong>Multisectorial por la Memoria (VM)<\/li>\n\n\n\n<li><strong>Hora del Acto Cultural: <\/strong>20 hs.<\/li>\n\n\n\n<li><strong>Lugar del Acto Cultural: <\/strong>Teatro TIM, Villa Mercedes<\/li>\n\n\n\n<li><strong>Entrada al Acto Cultural: <\/strong>Gratuita<\/li>\n\n\n\n<li><strong>Tem\u00e1tica Central: <\/strong>Memoria, verdad y justicia<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Movilizaci\u00f3n contra el Gobierno Estafador El pr\u00f3ximo lunes 24 de marzo, se llevar\u00e1 a cabo una movilizaci\u00f3n hist\u00f3rica en la Plaza San Mart\u00edn de Villa Mercedes, San Luis, a las 17 hs. El evento est\u00e1 organizado por el Multisectorial por la Memoria (VM), un colectivo que trabaja incansablemente para mantener viva la memoria de los &hellip;<\/p>\n","protected":false},"author":2,"featured_media":8749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,33],"tags":[],"class_list":["post-8746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stand-up-teatro-danzas","category-villa-mercedes-actualidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/03\/plaza-1.jpeg?fit=1080%2C1350&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/8746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=8746"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/8746\/revisions"}],"predecessor-version":[{"id":8750,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/8746\/revisions\/8750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/8749"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=8746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=8746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=8746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}