{"id":9673,"date":"2025-06-01T12:57:16","date_gmt":"2025-06-01T15:57:16","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=9673"},"modified":"2025-06-01T12:57:17","modified_gmt":"2025-06-01T15:57:17","slug":"el-gobierno-anuncio-un-aumento-salarial-para-medicos-del-garrahan-y-busca-desactivar-el-paro","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/el-gobierno-anuncio-un-aumento-salarial-para-medicos-del-garrahan-y-busca-desactivar-el-paro\/","title":{"rendered":"El Gobierno anunci\u00f3 un aumento salarial para m\u00e9dicos del Garrahan y busca desactivar el paro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La administraci\u00f3n del Hospital Garrahan inform\u00f3 este mi\u00e9rcoles un incremento salarial que eleva los haberes de los profesionales m\u00e9dicos a $1.300.000 a partir del 1 de julio, frente a los $797.000 que percib\u00edan hasta ahora. El anuncio se dio en medio de un conflicto con residentes y m\u00e9dicos que ven\u00edan reclamando mejoras laborales y salariales.<\/h2>\n\n\n\n<p>Seg\u00fan indicaron desde el directorio del hospital, el comunicado oficial fue \u201crevisado minuciosamente por la Casa Rosada\u201d y forma parte del plan de reorganizaci\u00f3n presupuestaria. En ese sentido, se indic\u00f3 que contin\u00faa la auditor\u00eda interna dentro del nosocomio para \u201cerradicar desv\u00edos presupuestarios y gastos superfluos\u201d, en sinton\u00eda con la pol\u00edtica de ajuste impulsada por el Gobierno nacional.<\/p>\n\n\n\n<p>Sin embargo, el texto incluy\u00f3 una frase que gener\u00f3 controversia: \u201cEste incremento es resultado de la planificaci\u00f3n presupuestaria dispuesta para esta etapa del a\u00f1o, no de las medidas de fuerza guionadas por la militancia kirchnerista que se esconde detr\u00e1s de los m\u00e9dicos\u201d. La declaraci\u00f3n fue le\u00edda por sectores gremiales como un intento de deslegitimar el reclamo sanitario mediante una interpretaci\u00f3n pol\u00edtica del conflicto.<\/p>\n\n\n\n<p>Durante los d\u00edas previos, la tensi\u00f3n se hab\u00eda intensificado con paros convocados por residentes y profesionales en reclamo de salarios justos y mejores condiciones laborales. Desde el Ejecutivo se hab\u00eda solicitado suspender la medida de fuerza por 48 horas para buscar una soluci\u00f3n negociada.<\/p>\n\n\n\n<p>Con el anuncio del aumento salarial, se espera una desactivaci\u00f3n del conflicto y el restablecimiento progresivo de la actividad habitual en el Garrahan, uno de los hospitales pedi\u00e1tricos m\u00e1s importantes del pa\u00eds.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n del Hospital Garrahan inform\u00f3 este mi\u00e9rcoles un incremento salarial que eleva los haberes de los profesionales m\u00e9dicos a $1.300.000 a partir del 1 de julio, frente a los $797.000 que percib\u00edan hasta ahora. El anuncio se dio en medio de un conflicto con residentes y m\u00e9dicos que ven\u00edan reclamando mejoras laborales y salariales. &hellip;<\/p>\n","protected":false},"author":12,"featured_media":9674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[31],"tags":[],"class_list":["post-9673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/06\/68399cf21e7d3_1180_664.jpg?fit=1180%2C664&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=9673"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9673\/revisions"}],"predecessor-version":[{"id":9675,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9673\/revisions\/9675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/9674"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=9673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=9673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=9673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}