{"id":9826,"date":"2025-06-11T14:13:22","date_gmt":"2025-06-11T17:13:22","guid":{"rendered":"https:\/\/calleangosta.com\/ca\/?p=9826"},"modified":"2025-06-11T16:36:36","modified_gmt":"2025-06-11T19:36:36","slug":"libertad-s-a","status":"publish","type":"post","link":"https:\/\/calleangosta.com\/ca\/libertad-s-a\/","title":{"rendered":"Libertad S.A."},"content":{"rendered":"\n<p class=\"has-text-align-right\">Por: Pablo Cufr\u00e9<\/p>\n\n\n\n<p>Se concret\u00f3 la proscripci\u00f3n. La decisi\u00f3n de la Corte Suprema de Justicia (CSJN) de ratificar, sin revisar el expediente, los fallos de las instancias anteriores que declararon culpable a la ex Presidenta Cristina Fern\u00e1ndez por la causa \u201cVialidad\u201d, dej\u00f3 en claro d\u00f3nde reside el poder, c\u00f3mo lo ejerce, a quienes percibe como sus enemigos y de qu\u00e9 manera va a tratar a cualquiera que se atreva a desafiarlo.<\/p>\n\n\n\n<p>Esta cr\u00f3nica de una condena anunciada se inici\u00f3 en el a\u00f1o 2007 cuando el flamante gobierno de CFK avanz\u00f3 con la cuesti\u00f3n de las retenciones a los exportadores de granos. En ese punto, los grupos de poder entendieron que la disputa no iba a tomar las mismas formas que hist\u00f3ricamente se hab\u00edan aplicado en el pa\u00eds para disciplinar a personas o grupos que les complicaran su status quo.<\/p>\n\n\n\n<p>Quien tuvo m\u00e1s claro que esta vez el cargo de Presidenta no era un puesto menor fue el principal controlante del grupo Clar\u00edn, el empresario H\u00e9ctor Magnetto quien, desde su multimedio y acompa\u00f1ado por los principales due\u00f1os de la Argentina, se fij\u00f3 como meta que Cristina terminara muerta o presa.<\/p>\n\n\n\n<p>Por supuesto ponerle un nombre y una cara ayuda a identificar al adversario, pero el \u00e1rbol no debe tapar el bosque. La historia argentina nos muestra que desde que se intent\u00f3 dise\u00f1ar al Estado-naci\u00f3n, la disputa por los beneficiarios del poder estaba planteada solamente entre los due\u00f1os de la tierra y cuando surg\u00eda alg\u00fan caudillo o referente que cuestionara el orden dado, se lo persegu\u00eda y silenciaba sin m\u00e1s.<\/p>\n\n\n\n<p>La elaboraci\u00f3n de la Constituci\u00f3n, hecha a imagen y semejanza de la norteamericana, intent\u00f3 legalizar ese orden establecido, generando ciertos derechos que aliviaran la tensi\u00f3n para una porci\u00f3n un poco mayor de la poblaci\u00f3n, pero tambi\u00e9n asegurarse que si otros mecanismos fallaban, siempre hubiera una instancia para limitar los avances populares. Ese poder del Estado es el judicial, cuyo \u00f3rgano m\u00e1ximo se llama Corte Suprema que, como si fuera un ente mon\u00e1rquico, de origen divino y decisiones inapelables, es el destinado a garantizar que el verdadero poder siga siendo incuestionable, bajo amenaza de condena.<\/p>\n\n\n\n<p>Fue el poder judicial, como fiel representante de la casta que domina el pa\u00eds, la herramienta utilizada esta vez para condenar a Cristina y enviar un mensaje disciplinador a toda la sociedad en general y a la dirigencia pol\u00edtica y sindical en particular. La ex Presidenta lo dej\u00f3 claro: \u201cEste triunvirato impresentable, son tres monigotes que responden a mandos naturales muy por arriba de ellos: el poder econ\u00f3mico concentrado de la Argentina\u00bb<\/p>\n\n\n\n<p>El modelo econ\u00f3mico instaurado por el otro \u201cmonigote del poder\u201d actualmente a cargo del Ejecutivo, que repite casi punto por punto lo ya hecho por los gobiernos de la dictadura c\u00edvico-militar, Menem y Macri, ha demostrado una y otra vez ser fallido en sus enunciados te\u00f3ricos, aunque siempre provechoso para un grupo muy peque\u00f1o de ganadores, y ahora no es distinto.<\/p>\n\n\n\n<p>Este modelo de empobrecimiento general necesita de la persecuci\u00f3n, la estigmatizaci\u00f3n, la violencia institucional y la pelea entre pares sociales para avanzar hasta el l\u00edmite de su ambici\u00f3n, sin preocuparse por las consecuencias que deja a su paso.<\/p>\n\n\n\n<p>La historia pendular de nuestro pa\u00eds ha completado un nuevo movimiento hacia uno de los lados y mal que les pese a muchos, no se va a quedar suspendida ni es definitiva.<\/p>\n\n\n\n<p>Sin embargo, la inevitable oscilaci\u00f3n hacia el lado contrario no debe dejarse librada a las leyes de la f\u00edsica. Debe ser planeada, imaginada, conducida y ejecutada por el movimiento pol\u00edtico in\u00e9dito que gener\u00f3 nuestro pa\u00eds, que tanto desconcierto y enojo les causa a las \u00e9lites, con la participaci\u00f3n y el compromiso de todas las expresiones populares que se propongan vivir en paz y armon\u00eda, generando trabajo digno y permitiendo que cada quien pueda realizarse individualmente, siempre en beneficio de la comunidad que integra.<\/p>\n\n\n\n<p>Vamos, hay mucho trabajo que hacer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Pablo Cufr\u00e9 Se concret\u00f3 la proscripci\u00f3n. La decisi\u00f3n de la Corte Suprema de Justicia (CSJN) de ratificar, sin revisar el expediente, los fallos de las instancias anteriores que declararon culpable a la ex Presidenta Cristina Fern\u00e1ndez por la causa \u201cVialidad\u201d, dej\u00f3 en claro d\u00f3nde reside el poder, c\u00f3mo lo ejerce, a quienes percibe como &hellip;<\/p>\n","protected":false},"author":2,"featured_media":9827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[31,23],"tags":[],"class_list":["post-9826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-opinion"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calleangosta.com\/ca\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-11-at-13.47.14.jpeg?fit=987%2C555&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/comments?post=9826"}],"version-history":[{"count":1,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9826\/revisions"}],"predecessor-version":[{"id":9828,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/posts\/9826\/revisions\/9828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media\/9827"}],"wp:attachment":[{"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/media?parent=9826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/categories?post=9826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calleangosta.com\/ca\/wp-json\/wp\/v2\/tags?post=9826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}